{"id":299,"date":"2017-12-21T17:28:08","date_gmt":"2017-12-21T20:28:08","guid":{"rendered":"http:\/\/revistaoropel.cl\/?p=299"},"modified":"2018-09-03T12:07:27","modified_gmt":"2018-09-03T15:07:27","slug":"santiago-traves-del-cine-pasado-inaprensible","status":"publish","type":"post","link":"https:\/\/revistaoropel.cl\/index.php\/2017\/12\/21\/santiago-traves-del-cine-pasado-inaprensible\/","title":{"rendered":"Santiago a trav\u00e9s del cine: un pasado inaprensible"},"content":{"rendered":"<p style=\"text-align: justify;\">El Santiago en el que vivimos ahora es completamente distinto a la ciudad en la que vivieron nuestros padres y abuelos. Esto pasa por cuestiones obvias, factores culturales, econ\u00f3micos, pol\u00edticos e hist\u00f3ricos. Hay una etapa de Santiago que el cine ha representado una y otra vez, el periodo de apogeo de la Unidad Popular y luego la \u00e9poca de dictadura c\u00edvico-militar. El Santiago de la Unidad Popular es visto como una ciudad en pugna, donde confluyen distintos puntos de vista a partir de pensamientos pol\u00edticos divergentes, no es en vano el r\u00f3tulo puesto a La Batalla de Chile, documental de Patricio Guzm\u00e1n, Santiago en ese entonces parec\u00eda un campo de batalla.<\/p>\n<p style=\"text-align: justify;\">A partir del an\u00e1lisis de cinco pel\u00edculas ubicadas en Santiago entre los a\u00f1os 1967 y 1985 trataremos de ver c\u00f3mo la ciudad ha mutado, y sobre todo, c\u00f3mo parece ser que el Santiago de la Unidad Popular es inaprensible a trav\u00e9s del cine ficci\u00f3n, tanto en el plano de lo cinematogr\u00e1fico como en el lenguaje. Las pel\u00edculas son: La Batalla de Chile de Patricio Guzm\u00e1n, Palomita Blanca de Ra\u00fal Ru\u00edz, Largo Viaje de Patricio Kaulen, Machuca de Andr\u00e9s Wood, y Cabros de Mierda de Gonzalo Justiniano.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-305 size-full\" src=\"https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/palomita-blanca.jpg\" alt=\"\" width=\"858\" height=\"630\" srcset=\"https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/palomita-blanca.jpg 858w, https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/palomita-blanca-300x220.jpg 300w, https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/palomita-blanca-768x564.jpg 768w\" sizes=\"auto, (max-width: 858px) 100vw, 858px\" \/><\/p>\n<p style=\"text-align: justify;\">Creo que hoy el Santiago de la Unidad Popular es irreproducible, solo imaginable desde el archivo (narrativo, audiovisual etc.) o la oralidad. Palomita Blanca muestra una ciudad diversa, en pugna, pero desde un punto de vista subjetivo, una ciudad que est\u00e1 poblada, en la que el contexto social interpela a sus habitantes, se diferencia con La Batalla de Chile en un mont\u00f3n de cosas, partiendo por ser una ficci\u00f3n y adem\u00e1s una adaptaci\u00f3n casi sat\u00edrica de una novela que retrata el conflicto de clase desde el punto de vista de un romance, tal como hoy lo hace la TV chilena con telenovelas como \u201cDama y obrero\u201d o \u201cPobre y rico\u201d, sin la s\u00e1tira por supuesto. La ciudad es mostrada por Ru\u00edz desde el punto de vista -siempre subjetivo- de los personajes, al contrario de La Batalla de Chile, donde la ciudad parece ser el protagonista principal, una ciudad en disputa constante entre las personas que est\u00e1n, a diferencia de hoy, involucradas directamente en el devenir pol\u00edtico del pa\u00eds. En Palomita Blanca y la filmograf\u00eda de Ru\u00edz hay adem\u00e1s un foco puesto en el lenguaje, en el c\u00f3mo se dicen las cosas, m\u00e1s que en el qu\u00e9 se dice, m\u00e1s en el significante que en el significado, los personajes y la ciudad se expresan de una manera claramente distinguible.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-302 size-full\" src=\"https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/boc123_014.jpg\" alt=\"\" width=\"1172\" height=\"800\" srcset=\"https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/boc123_014.jpg 1172w, https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/boc123_014-300x205.jpg 300w, https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/boc123_014-768x524.jpg 768w, https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/boc123_014-1024x699.jpg 1024w, https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/boc123_014-1040x710.jpg 1040w\" sizes=\"auto, (max-width: 1172px) 100vw, 1172px\" \/><\/p>\n<p style=\"text-align: justify;\">La Batalla de Chile es tambi\u00e9n una batalla ling\u00fc\u00edstica, y se da tanto en el espacio p\u00fablico como en el privado. A trav\u00e9s de m\u00e1s de 6 horas de pel\u00edcula Patricio Guzm\u00e1n nos acerca la pugna de las calles santiaguinas desde los momentos previos a la elecci\u00f3n de Allende hasta el Golpe de Estado, a partir de entrevistas, simulando ser de un canal de televisi\u00f3n, o simplemente meti\u00e9ndose en distintos recovecos de la ciudad. Aqu\u00ed el punto de vista lo sostiene la \u00f3ptica documental que intenta utilizar la realidad para extraer de ella su intimidad, y Guzm\u00e1n lo logra \u2013siempre lo hace-.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-301 size-full\" src=\"https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/09.jpg\" alt=\"\" width=\"858\" height=\"496\" srcset=\"https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/09.jpg 858w, https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/09-300x173.jpg 300w, https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/09-768x444.jpg 768w\" sizes=\"auto, (max-width: 858px) 100vw, 858px\" \/>Largo Viaje, es una pel\u00edcula que acaba de cumplir 50 a\u00f1os, dirigida por Patricio Kaulen, narra la historia de un ni\u00f1o cuya madre est\u00e1 embarazada esperando un ni\u00f1o. A partir de la sucesi\u00f3n de cortes r\u00e1pidos y breves presentaciones de personajes nos adentramos en la historia. El ni\u00f1o nace muerto y se realiza el ritual del angelito, luego de esto llevan al hermano al cementerio y \u00e9l se queda con las alitas del hermano, las cuales seg\u00fan el abuelo sirven para ir al cielo. El ni\u00f1o se pierde por Santiago tratando de que no le roben las alitas. Pasa por un mont\u00f3n de lugares, La Vega, el Mapocho, el centro lleno de escaparates, y no sabe c\u00f3mo volver a su casa. Finalmente termina perdido y sin las alitas de su hermano. En la pel\u00edcula el punto de vista es el del ni\u00f1o extraviado en esta ciudad, que al igual que en Palomita Blanca y La Batalla de Chile, tiene mucho movimiento, est\u00e1 alborotada de gente en las calles, y es una ciudad en pugna constante. Al igual que en la pel\u00edcula de Ru\u00edz el lenguaje de los personajes es de una riqueza impresionante.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-304 size-full\" src=\"https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/machuca_03.jpg\" alt=\"\" width=\"1643\" height=\"1066\" srcset=\"https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/machuca_03.jpg 1643w, https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/machuca_03-300x195.jpg 300w, https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/machuca_03-768x498.jpg 768w, https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/machuca_03-1024x664.jpg 1024w, https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/machuca_03-1040x675.jpg 1040w, https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/machuca_03-1200x779.jpg 1200w\" sizes=\"auto, (max-width: 1643px) 100vw, 1643px\" \/><\/p>\n<p style=\"text-align: justify;\">Machuca, pel\u00edcula taquillera de Andr\u00e9s Wood, se cuenta siempre desde el punto de vista subjetivo, se explica su \u00e9xito en taquilla porque aspira a representar a toda la poblaci\u00f3n que vivi\u00f3 la dictadura, y plantea una realidad en la que todas las personas de alguna manera \u201csufren\u201d la dictadura. As\u00ed el ni\u00f1o de la clase alta, el cuico, sufre el oprobio de los personajes de la clase baja, y los personajes de la clase baja experimentan el sufrimiento -a estas alturas obvio- de los distintos elementos represores, autoritarios y fascistas empleados por los militares y su reproducci\u00f3n en la actitud y valores de la burgues\u00eda nacional.<\/p>\n<p style=\"text-align: justify;\">Machuca nunca se posiciona realmente con un discurso, no tiene por qu\u00e9 hacerlo, es una ficci\u00f3n del siglo XXI, Andr\u00e9s Wood logra lo que quiere, que una pel\u00edcula sobre la dictadura sea la m\u00e1s vista de la historia (hasta ese entonces), poder hablar de la dictadura sin posicionarse directamente a favor o en contra de la Unidad Popular o la dictadura c\u00edvico-militar, y no s\u00e9 si es por su punto de vista excesivamente subjetivo o por incapacidad narrativa-t\u00e9cnica, pero en Machuca no existe el mismo Santiago que en La Batalla de Chile o Palomita Blanca. En Machuca hay demasiado siglo XXI, demasiada social-democracia, demasiada pol\u00edtica de los acuerdos y demasiada transici\u00f3n, en este sentido, Machuca ejemplifica la visi\u00f3n de la anhelada reconciliaci\u00f3n-pa\u00eds propuesta desde el PS a la derecha, y no s\u00e9 si lo hace a prop\u00f3sito. Incluso si lo llevamos al plano t\u00e9cnico, mientras Guzm\u00e1n, Kaulen y Ru\u00edz ten\u00edan una propuesta t\u00e9cnica clara y al mismo tiempo arriesgada, Wood hace simplemente lo que pide la galer\u00eda, un drama en tres actos centrada en la psicolog\u00eda de los personajes, en sus falencias y virtudes, y c\u00f3mo estos chocan tanto en su relaci\u00f3n entre pares como con la sociedad. Adem\u00e1s busca reeditar el lenguaje de la dictadura y la Unidad Popular para dar m\u00e1s realismo y coherencia a la pel\u00edcula, pero \u00bfes acaso pertinente o siquiera alcanzable este prop\u00f3sito? Creo sinceramente que Wood repite la f\u00f3rmula del drama <em>pityful<\/em> gringo, busca emocionar, busca hacer que la gente vuelva a hablar sobre su vida en ese tiempo, busca reeditar vivencias en pos de una especie de saneamiento secular de la sociedad, no en vano es la pel\u00edcula chilena mejor punteada de IMDB, el <em>establishment<\/em> por excelencia.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-300 size-full\" src=\"https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/2c76b2d9-d942-437c-9bc1-9104600c4c30-e1499813094255.png\" alt=\"\" width=\"680\" height=\"383\" srcset=\"https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/2c76b2d9-d942-437c-9bc1-9104600c4c30-e1499813094255.png 680w, https:\/\/revistaoropel.cl\/wp-content\/uploads\/2017\/12\/2c76b2d9-d942-437c-9bc1-9104600c4c30-e1499813094255-300x169.png 300w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/p>\n<p style=\"text-align: justify;\">Cabros de Mierda es la \u00faltima pel\u00edcula de Gonzalo Justiniano, estrenada este a\u00f1o (2017). Narra la historia de un misionero estadounidense que llega a La Victoria en plena dictadura. Lo acogen en su casa una familia amplia compuesta por mujeres y ni\u00f1os. La pel\u00edcula es, en definitiva, lo contrario de Machuca, se posiciona claramente con una visi\u00f3n de la dictadura, desde la visi\u00f3n de la resistencia en las poblaciones en los 80. Sin embargo propone un punto de vista extremadamente cerrado, una resistencia perfecta, donde no hay disidentes, no hay dudas, s\u00f3lo hay convicci\u00f3n y lucha en la poblaci\u00f3n. La pel\u00edcula est\u00e1 a cada segundo intentando develar desde qu\u00e9 posici\u00f3n pol\u00edtica se aborda, y lo dice a gritos. Y a pesar de tener un posicionamiento muy distinto al de Machuca, cae en los mismos lugares comunes. Uno de ellos es el amor prohibido que tiene el misionero gringo (interpretado horriblemente por un chileno) con la pobladora, \u201cLa francesita\u201d, la cual en el d\u00eda parece una mujer \u201cnormal\u201d y en la noche se organiza para pintar los muros de la poblaci\u00f3n. Adem\u00e1s Justiniano intenta reciclar videos de protestas filmados en su juventud y los hace pasar como si fuesen del misionero gringo en la ficci\u00f3n, un ejercicio horroroso teniendo en cuenta que no es lo mismo que te filme alguien conocido, propio de tu poblaci\u00f3n, que un misionero gringo reci\u00e9n llegado, menos si se trata de una protesta, menos en un pa\u00eds en dictadura, un insulto al ejercicio documental. Estos factores configuran que Cabros de Mierda sea a t\u00edtulo personal la peor ficci\u00f3n que hay sobre la dictadura, s\u00f3lo comparable a un lavado de cerebro, no hay necesidad de que sea una pel\u00edcula, mejor ser\u00eda hacer un libro, una performance, una conmemoraci\u00f3n. Al cine no le aporta nada. Es cine para convencidos, un panfleto que no interpela a nadie de los que se busca interpelar. Justiniano entrega todo masticado, no deja al espectador nada por hacer, solo tragar su testimonio.<\/p>\n<p style=\"text-align: justify;\">En definitiva, la ficci\u00f3n sobre la dictadura deja mucho que desear, solo el documental ha logrado ahondar en esa \u00e9poca sin distorsionarla en el intento, en parte se debe a que en el documental pueden ser las mismas personas que vivieron esta \u00e9poca las que hablan, narran y vuelven a vivir (por ejemplo en La ciudad de los fot\u00f3grafos, Nostalgia de la luz, \u00c9l bot\u00f3n de N\u00e1car, Guerrero, El color del camale\u00f3n, El diario de Agust\u00edn, etc.), quiz\u00e1s por eso parece ser Patricio Guzm\u00e1n quien mejor puede hablar de la \u00e9poca. No es que la ficci\u00f3n sea incapaz de revisitar temas hist\u00f3ricos y hacerlo bien, los alemanes en eso son escuela, tanto La Ca\u00edda como La Vida de los Otros son tremendos ejemplos de ficciones que se meten justo ah\u00ed en el modo de sentir y pensar una \u00e9poca, en su mismo esp\u00edritu, no intentan hacerlo desde el presente, no muestran la hilacha de querer ser wannabe\u2019s en Berl\u00edn o Venecia, hacen simplemente lo que tienen que hacer.<\/p>\n<p style=\"text-align: justify;\">La Batalla de Chile nos demuestra c\u00f3mo el debate c\u00edvico actual est\u00e1 completamente empobrecido respecto a los a\u00f1os de la Unidad Popular, y eso lo vemos en el plano de la argumentaci\u00f3n. En cuanto a la expresi\u00f3n pasa lo mismo, Palomita Blanca es ejemplo de ello, as\u00ed como otras pel\u00edculas de la \u00e9poca como Tres Tristes Tigres, Valpara\u00edso mi Amor y Largo Viaje; la riqueza del espectro de expresi\u00f3n que conten\u00eda la globalidad de la sociedad chilena de la \u00e9poca no es nada comparable a la de hoy, sociedad que se expresa a trav\u00e9s de abreviaciones e im\u00e1genes m\u00e1s que en un lenguaje anclado en la territorialidad. Los memes, los chats y los \u201cemojis\u201d son signo inequ\u00edvoco de esto, la gente no se esfuerza por expresarse de manera clara a trav\u00e9s de palabras, sino que priman modos de representaci\u00f3n que son aceptados socialmente y que tienen significados un\u00edvocos. No es raro ver que la comunicaci\u00f3n entre personas puede darse simplemente a trav\u00e9s de \u00edconos, signos y s\u00edmbolos que no forman parte del lenguaje, por ejemplo, poner un dibujo pixelado de un coraz\u00f3n y una \u201ccarita feliz\u201d basta para decir \u201cestoy contento y siento alguna especie de querer\/amor por ti\u201d sin tener que entrar en emplear tonos, gestos o palabras, algo que hasta hace 20 a\u00f1os era totalmente ajeno a la comunicaci\u00f3n interpersonal. Hace poco se estren\u00f3 una pel\u00edcula que se basaba en la personificaci\u00f3n de los \u201cemojis\u201d, siendo personajes dentro de una trama bastante tragic\u00f3mica. Tambi\u00e9n el cine chileno y su paulatina incorporaci\u00f3n de elementos de las redes sociales en su narrativa es una se\u00f1al de que los recursos cinematogr\u00e1ficos y narrativos se han vuelto menos sofisticados que antes, tal y como sucede con la comunicaci\u00f3n humana en su contenido. (ej. pel\u00edculas de Nicol\u00e1s L\u00f3pez, Sebasti\u00e1n Badilla, Fabrizio Copano y su s\u00e9quito, etc.)<\/p>\n<p style=\"text-align: justify;\">Parece ser que el Santiago de la Unidad Popular y la dictadura es inabarcable para la ficci\u00f3n actual, ni Machuca con su grandilocuente producci\u00f3n para escenificar marchas, ni Cabros de Mierda reciclando grabaciones de la \u00e9poca, logran llegar a un Santiago parecido al que retratan Ru\u00edz, Kaulen y Guzm\u00e1n. No lo logran ni en la manera de hacer cine ni en el plano del lenguaje.<\/p>\n<p style=\"text-align: justify;\">Para concluir, hay reminiscencias de la dictadura en el lenguaje cinematogr\u00e1fico y art\u00edstico chileno en general, puede considerarse el periodo como una interrupci\u00f3n radical en el desarrollo art\u00edstico e intelectual del pa\u00eds, no es casualidad que los militares quemaran libros en las calles, es una se\u00f1al simb\u00f3lica pero sumamente directa, como dec\u00eda el dictador: \u201ca la universidad se va a estudiar\u201d y hasta ah\u00ed no m\u00e1s. Luego de esta categ\u00f3rica interrupci\u00f3n, es dif\u00edcil o casi imposible, volver a evocar el modo de sentir y pensar una \u00e9poca que es tan distinta a la actual, m\u00e1s a\u00fan en una ciudad que se ha renovado en una direcci\u00f3n que lo que menos quiere es recordar. Quiz\u00e1s el pasado es esencialmente inaprensible.<\/p>\n<p><strong>Por Miguel \u00c1ngel Guti\u00e9rrez.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Santiago en el que vivimos ahora es completamente distinto a la ciudad en la que vivieron nuestros padres y abuelos. Esto pasa por cuestiones obvias, factores culturales, econ\u00f3micos, pol\u00edticos e hist\u00f3ricos. Hay una etapa de Santiago que el cine ha representado una y otra vez, el periodo de apogeo de la Unidad Popular y [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":405,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[88,84,14,78,79,81,85,83,80,86,87,82,77],"class_list":["post-299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine","tag-andres-wood","tag-blanca","tag-cine","tag-ciudad","tag-guzman","tag-justiniano","tag-largo-viaje","tag-palomita","tag-patricio","tag-patricio-kaulen","tag-raul","tag-ruiz","tag-santiago"],"_links":{"self":[{"href":"https:\/\/revistaoropel.cl\/index.php\/wp-json\/wp\/v2\/posts\/299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaoropel.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaoropel.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaoropel.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaoropel.cl\/index.php\/wp-json\/wp\/v2\/comments?post=299"}],"version-history":[{"count":4,"href":"https:\/\/revistaoropel.cl\/index.php\/wp-json\/wp\/v2\/posts\/299\/revisions"}],"predecessor-version":[{"id":419,"href":"https:\/\/revistaoropel.cl\/index.php\/wp-json\/wp\/v2\/posts\/299\/revisions\/419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaoropel.cl\/index.php\/wp-json\/wp\/v2\/media\/405"}],"wp:attachment":[{"href":"https:\/\/revistaoropel.cl\/index.php\/wp-json\/wp\/v2\/media?parent=299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaoropel.cl\/index.php\/wp-json\/wp\/v2\/categories?post=299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaoropel.cl\/index.php\/wp-json\/wp\/v2\/tags?post=299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}